{"id":373,"count":1,"description":"","link":"https:\/\/blogit.metropolia.fi\/robologi\/tag\/ugv-tekniikka\/","name":"UGV-tekniikka","slug":"ugv-tekniikka","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UGV-tekniikka arkistot - Robologi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogit.metropolia.fi\/robologi\/tag\/ugv-tekniikka\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UGV-tekniikka arkistot - Robologi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogit.metropolia.fi\/robologi\/tag\/ugv-tekniikka\/\" \/>\n<meta property=\"og:site_name\" content=\"Robologi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/robologi\\\/tag\\\/ugv-tekniikka\\\/\",\"url\":\"https:\\\/\\\/blogit.metropolia.fi\\\/robologi\\\/tag\\\/ugv-tekniikka\\\/\",\"name\":\"UGV-tekniikka arkistot - Robologi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/robologi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/robologi\\\/tag\\\/ugv-tekniikka\\\/#breadcrumb\"},\"inLanguage\":\"fi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/robologi\\\/tag\\\/ugv-tekniikka\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/blogit.metropolia.fi\\\/robologi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UGV-tekniikka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/robologi\\\/#website\",\"url\":\"https:\\\/\\\/blogit.metropolia.fi\\\/robologi\\\/\",\"name\":\"Robologi\",\"description\":\"Valmiuksia ja mahdollisuuksia tutkimassa ja kehitt\u00e4m\u00e4ss\u00e4\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogit.metropolia.fi\\\/robologi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UGV-tekniikka arkistot - Robologi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogit.metropolia.fi\/robologi\/tag\/ugv-tekniikka\/","og_locale":"fi_FI","og_type":"article","og_title":"UGV-tekniikka arkistot - Robologi","og_url":"https:\/\/blogit.metropolia.fi\/robologi\/tag\/ugv-tekniikka\/","og_site_name":"Robologi","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogit.metropolia.fi\/robologi\/tag\/ugv-tekniikka\/","url":"https:\/\/blogit.metropolia.fi\/robologi\/tag\/ugv-tekniikka\/","name":"UGV-tekniikka arkistot - Robologi","isPartOf":{"@id":"https:\/\/blogit.metropolia.fi\/robologi\/#website"},"breadcrumb":{"@id":"https:\/\/blogit.metropolia.fi\/robologi\/tag\/ugv-tekniikka\/#breadcrumb"},"inLanguage":"fi"},{"@type":"BreadcrumbList","@id":"https:\/\/blogit.metropolia.fi\/robologi\/tag\/ugv-tekniikka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/blogit.metropolia.fi\/robologi\/"},{"@type":"ListItem","position":2,"name":"UGV-tekniikka"}]},{"@type":"WebSite","@id":"https:\/\/blogit.metropolia.fi\/robologi\/#website","url":"https:\/\/blogit.metropolia.fi\/robologi\/","name":"Robologi","description":"Valmiuksia ja mahdollisuuksia tutkimassa ja kehitt\u00e4m\u00e4ss\u00e4","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogit.metropolia.fi\/robologi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"}]}},"lang":"fi","translations":{"fi":373},"_links":{"self":[{"href":"https:\/\/blogit.metropolia.fi\/robologi\/wp-json\/wp\/v2\/tags\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogit.metropolia.fi\/robologi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogit.metropolia.fi\/robologi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogit.metropolia.fi\/robologi\/wp-json\/wp\/v2\/posts?tags=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}