{"id":309,"count":2,"description":"","link":"https:\/\/blogit.metropolia.fi\/rehablogi\/tag\/terapia\/","name":"terapia","slug":"terapia","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>terapia arkistot - Rehablogi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogit.metropolia.fi\/rehablogi\/tag\/terapia\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"terapia arkistot - Rehablogi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogit.metropolia.fi\/rehablogi\/tag\/terapia\/\" \/>\n<meta property=\"og:site_name\" content=\"Rehablogi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/rehablogi\\\/tag\\\/terapia\\\/\",\"url\":\"https:\\\/\\\/blogit.metropolia.fi\\\/rehablogi\\\/tag\\\/terapia\\\/\",\"name\":\"terapia arkistot - Rehablogi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/rehablogi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/rehablogi\\\/tag\\\/terapia\\\/#breadcrumb\"},\"inLanguage\":\"fi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/rehablogi\\\/tag\\\/terapia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/blogit.metropolia.fi\\\/rehablogi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"terapia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/rehablogi\\\/#website\",\"url\":\"https:\\\/\\\/blogit.metropolia.fi\\\/rehablogi\\\/\",\"name\":\"Rehablogi\",\"description\":\"Kuntoutuksen ja terveydenhuollon hyvi\u00e4 k\u00e4yt\u00e4nteit\u00e4 kehitt\u00e4m\u00e4ss\u00e4\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogit.metropolia.fi\\\/rehablogi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"terapia arkistot - Rehablogi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogit.metropolia.fi\/rehablogi\/tag\/terapia\/","og_locale":"fi_FI","og_type":"article","og_title":"terapia arkistot - Rehablogi","og_url":"https:\/\/blogit.metropolia.fi\/rehablogi\/tag\/terapia\/","og_site_name":"Rehablogi","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogit.metropolia.fi\/rehablogi\/tag\/terapia\/","url":"https:\/\/blogit.metropolia.fi\/rehablogi\/tag\/terapia\/","name":"terapia arkistot - Rehablogi","isPartOf":{"@id":"https:\/\/blogit.metropolia.fi\/rehablogi\/#website"},"breadcrumb":{"@id":"https:\/\/blogit.metropolia.fi\/rehablogi\/tag\/terapia\/#breadcrumb"},"inLanguage":"fi"},{"@type":"BreadcrumbList","@id":"https:\/\/blogit.metropolia.fi\/rehablogi\/tag\/terapia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/blogit.metropolia.fi\/rehablogi\/"},{"@type":"ListItem","position":2,"name":"terapia"}]},{"@type":"WebSite","@id":"https:\/\/blogit.metropolia.fi\/rehablogi\/#website","url":"https:\/\/blogit.metropolia.fi\/rehablogi\/","name":"Rehablogi","description":"Kuntoutuksen ja terveydenhuollon hyvi\u00e4 k\u00e4yt\u00e4nteit\u00e4 kehitt\u00e4m\u00e4ss\u00e4","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogit.metropolia.fi\/rehablogi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"}]}},"lang":"fi","translations":{"fi":309},"_links":{"self":[{"href":"https:\/\/blogit.metropolia.fi\/rehablogi\/wp-json\/wp\/v2\/tags\/309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogit.metropolia.fi\/rehablogi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogit.metropolia.fi\/rehablogi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogit.metropolia.fi\/rehablogi\/wp-json\/wp\/v2\/posts?tags=309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}