{"id":507,"count":1,"description":"","link":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/tag\/lisenssi\/","name":"lisenssi","slug":"lisenssi","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>lisenssi arkistot - Hiilt\u00e4 ja timanttia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/tag\/lisenssi\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lisenssi arkistot - Hiilt\u00e4 ja timanttia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/tag\/lisenssi\/\" \/>\n<meta property=\"og:site_name\" content=\"Hiilt\u00e4 ja timanttia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/hiilta-ja-timanttia\\\/tag\\\/lisenssi\\\/\",\"url\":\"https:\\\/\\\/blogit.metropolia.fi\\\/hiilta-ja-timanttia\\\/tag\\\/lisenssi\\\/\",\"name\":\"lisenssi arkistot - Hiilt\u00e4 ja timanttia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/hiilta-ja-timanttia\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/hiilta-ja-timanttia\\\/tag\\\/lisenssi\\\/#breadcrumb\"},\"inLanguage\":\"fi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/hiilta-ja-timanttia\\\/tag\\\/lisenssi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/blogit.metropolia.fi\\\/hiilta-ja-timanttia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"lisenssi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogit.metropolia.fi\\\/hiilta-ja-timanttia\\\/#website\",\"url\":\"https:\\\/\\\/blogit.metropolia.fi\\\/hiilta-ja-timanttia\\\/\",\"name\":\"Hiilt\u00e4 ja timanttia\",\"description\":\"Opittajat pedagogiikan rajapinnoilla\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogit.metropolia.fi\\\/hiilta-ja-timanttia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"lisenssi arkistot - Hiilt\u00e4 ja timanttia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/tag\/lisenssi\/","og_locale":"fi_FI","og_type":"article","og_title":"lisenssi arkistot - Hiilt\u00e4 ja timanttia","og_url":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/tag\/lisenssi\/","og_site_name":"Hiilt\u00e4 ja timanttia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/tag\/lisenssi\/","url":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/tag\/lisenssi\/","name":"lisenssi arkistot - Hiilt\u00e4 ja timanttia","isPartOf":{"@id":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/#website"},"breadcrumb":{"@id":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/tag\/lisenssi\/#breadcrumb"},"inLanguage":"fi"},{"@type":"BreadcrumbList","@id":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/tag\/lisenssi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/"},{"@type":"ListItem","position":2,"name":"lisenssi"}]},{"@type":"WebSite","@id":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/#website","url":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/","name":"Hiilt\u00e4 ja timanttia","description":"Opittajat pedagogiikan rajapinnoilla","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"}]}},"lang":"fi","translations":{"fi":507},"_links":{"self":[{"href":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/wp-json\/wp\/v2\/tags\/507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogit.metropolia.fi\/hiilta-ja-timanttia\/wp-json\/wp\/v2\/posts?tags=507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}